{"id":12599,"date":"2024-03-20T07:37:14","date_gmt":"2024-03-20T07:37:14","guid":{"rendered":"https:\/\/www.hotelcesaraugusta.com\/?page_id=12599"},"modified":"2024-03-22T07:34:35","modified_gmt":"2024-03-22T07:34:35","slug":"ton-hotel-de-confiance-a-saragosse","status":"publish","type":"page","link":"https:\/\/www.hotelcesaraugusta.com\/fr\/","title":{"rendered":"Ton h\u00f4tel de confiance \u00e0 Saragosse"},"content":{"rendered":"<section class=\"l-section wpb_row us_custom_5b3dd798 height_full valign_top width_full\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row type_default valign_top\"><div class=\"vc_col-sm-12 wpb_column vc_column_container animate_afl\" style=\"animation-delay:0.5s;\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-grid type_carousel layout_9078 no_gap\" id=\"us_grid_1\" data-grid-filter=\"false\"><style id=\"us_grid_1_css\">#us_grid_1 .owl-nav div{font-size:1.8rem}<\/style><style>.layout_9078 .w-grid-item-h{}<\/style><div class=\"w-grid-list owl-carousel navstyle_circle navpos_inside\" ><article class=\"w-grid-item post-12630 sliders type-sliders status-publish hentry\" data-id=\"12630\">\n\t<div class=\"w-grid-item-h\">\n\t\t\t\t<div class=\"w-post-elm post_content usg_post_content_1\" ><section class=\"l-section wpb_row height_full valign_top with_img\"><div class=\"l-section-img\" style=\"background-image: url(https:\/\/www.hotelcesaraugusta.com\/wp-content\/uploads\/2023\/03\/slider-1-hotelcesaraugusta-2.jpg);background-repeat: no-repeat;\" data-img-width=\"1440\" data-img-height=\"809\"><\/div><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row type_default valign_top\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><\/div><\/section>\n<\/div>\t<\/div>\n<\/article>\n<\/div><div class=\"g-preloader type_custom\">\n\t<div><img width=\"200\" height=\"91\" src=\"data:image\/svg+xml,%3Csvg xmlns=%22http:\/\/www.w3.org\/2000\/svg%22 viewBox=%220 0 200 91%22%3E%3C\/svg%3E\" data-lazy-type=\"image\" data-src=\"https:\/\/www.hotelcesaraugusta.com\/wp-content\/uploads\/2020\/09\/logo-hotel-cesaraugusta.jpg\" class=\"lazy lazy-hidden g-placeholder\" alt=\"hotel cesaraugusta\" loading=\"lazy\" \/><\/div>\n<\/div>\n\t<div class=\"w-grid-json hidden\" onclick='return {&quot;action&quot;:&quot;us_ajax_grid&quot;,&quot;ajax_url&quot;:&quot;https:\\\/\\\/www.hotelcesaraugusta.com\\\/wp-admin\\\/admin-ajax.php&quot;,&quot;infinite_scroll&quot;:0,&quot;max_num_pages&quot;:1,&quot;pagination&quot;:&quot;none&quot;,&quot;permalink_url&quot;:&quot;https:\\\/\\\/www.hotelcesaraugusta.com\\\/fr\\\/wp-json\\\/wp\\\/v2\\\/pages\\\/12599\\\/&quot;,&quot;template_vars&quot;:{&quot;columns&quot;:&quot;1&quot;,&quot;exclude_items&quot;:&quot;none&quot;,&quot;img_size&quot;:&quot;default&quot;,&quot;items_layout&quot;:&quot;9078&quot;,&quot;items_offset&quot;:&quot;1&quot;,&quot;overriding_link&quot;:&quot;none&quot;,&quot;post_id&quot;:12599,&quot;query_args&quot;:{&quot;post_type&quot;:[&quot;sliders&quot;],&quot;post_status&quot;:[&quot;publish&quot;],&quot;orderby&quot;:{&quot;date&quot;:&quot;DESC&quot;},&quot;posts_per_page&quot;:&quot;10&quot;},&quot;type&quot;:&quot;carousel&quot;,&quot;us_grid_ajax_index&quot;:1,&quot;us_grid_filter_params&quot;:null,&quot;us_grid_index&quot;:1,&quot;_us_grid_post_type&quot;:&quot;sliders&quot;,&quot;lang&quot;:&quot;fr&quot;},&quot;carousel_settings&quot;:{&quot;autoHeight&quot;:0,&quot;autoplay&quot;:0,&quot;carousel_fade&quot;:0,&quot;center&quot;:0,&quot;dots&quot;:0,&quot;items&quot;:&quot;1&quot;,&quot;loop&quot;:false,&quot;nav&quot;:1,&quot;slideby&quot;:&quot;1&quot;,&quot;smooth_play&quot;:0,&quot;speed&quot;:250,&quot;timeout&quot;:3000,&quot;transition&quot;:&quot;&quot;},&quot;carousel_breakpoints&quot;:{&quot;1200&quot;:{&quot;items&quot;:1},&quot;900&quot;:{&quot;autoHeight&quot;:0,&quot;autoplay&quot;:1,&quot;autoplayHoverPause&quot;:1,&quot;items&quot;:&quot;1&quot;,&quot;loop&quot;:true},&quot;600&quot;:{&quot;autoHeight&quot;:0,&quot;autoplay&quot;:1,&quot;autoplayHoverPause&quot;:1,&quot;items&quot;:&quot;1&quot;,&quot;loop&quot;:true},&quot;0&quot;:{&quot;autoHeight&quot;:0,&quot;autoplay&quot;:1,&quot;autoplayHoverPause&quot;:1,&quot;items&quot;:1,&quot;loop&quot;:true}}}'><\/div>\n<\/div><div class=\"g-cols wpb_row  us_custom_58dc4050 type_default valign_top vc_inner booking_box has_text_color\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column us_custom_593671af\" ><div class=\"wpb_wrapper\"><h1 style=\"font-size: max(4vw, 40px);\">H\u00d4TEL CESARAUGUSTA<br \/>\nTON H\u00d4TEL DE CONFIANCE \u00c0 SARAGOSSE<\/h1>\n<p><span style=\"font-size: 1.2rem;\">Chambres situ\u00e9es au centre-ville<\/span><\/p>\n<\/div><\/div>\n\n\n\t<!-- FONT AWSOME -->\n\n\t<link href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/4.7.0\/css\/font-awesome.css\" rel=\"stylesheet\"\/>\n\n\n\n\t<!-- MOMENT JS -->\n\n\t<script src=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/moment.js\/2.13.0\/moment-with-locales.min.js\"><\/script>\n\n\n\n\t\n\n\n\n\n\n\n\t\t<div id=\"search_room_box\">\n\n\t\t\n\n\t\t\t<form name=\"formSearch\" id=\"formSearch\" action=\"https:\/\/booking.roomcloud.net\/be\/se2\/hotel.jsp\" method=\"post\">\n\n\n\n\t\t\t\t<input type=\"hidden\" name=\"curr\" value=\"EUR\">\n\n\t\t\t\t<input type=\"hidden\" name=\"lang\" value=\"fr\">\n\n\n\n\t\t\t\t<input type=\"hidden\" name=\"showCrossed\" id=\"showCrossed\" value=\"\">\n\n\n\n\t\t\t\t<div id=\"search-items\">\n\n\n\n\t\t\t\t\t<div id=\"research-tab\">\n\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t<div class=\"rc-row\">\n\n\n\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t<div class=\"rc-col-xs-12 rc-col-sm-6 rc-col-md-3 rc-col-lg-3\" id=\"search_group_div\">\t\n\n\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t<div class=\"rc-input-group\" id=\"calendar_search_group\">\n\n\t\t\t\t\t\t\t\t\t\t<span class=\"input-group-addon\" id=\"calendar_search_span\" ><i class=\"fa fa-calendar dates_calendar src-icon\" aria-hidden=\"true\"><\/i><\/span>\n\n\t\t\t\t\t\t\t\t\t\t<label class=\"for\" for=\"search_calendar\">.<\/label><input class=\"form-control\" name=\"search_calendar\" id=\"search_calendar\" value=\"\" autocomplete=\"off\" onfocus=\"blur();\"\/>\n\n\t\t\t\t\t\t\t\t\t\t<input type=\"hidden\" name=\"checkin\" id=\"checkin\">\n\n\t\t\t\t\t\t\t\t\t\t<input type=\"hidden\" name=\"checkout\" id=\"checkout\"> \n\n\t\t\t\t\t\t\t\t\t\t<input type=\"hidden\" name=\"hotel\" value=\"16615\">\n\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t<\/div>\t\t\n\n\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\n\n\n\n\t\t\t\t\t\t\n\n\t\t\n\n\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t<div class=\"rc-col-xs-12 rc-col-sm-6 rc-col-md-4 rc-col-lg-3\"  id=\"rooms_search\">\n\n\t\t\n\n\t\t\t\t\t\t\t\t<div class=\"rc-dropdown\">\n\n\t\t\n\n\t\t\t\t\t\t\t\t\t<div class=\"rc-input-group\" id=\"travelers_group\">\n\n\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t<span class=\"input-group-addon\" ><i class=\"fa fa-male src-icon\" aria-hidden=\"true\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t<label class=\"for\" for=\"travelers\">.<\/label>\n\t\t\t\t\t\t\t\t\t\t<input class=\"form-control\" id=\"travelers\" autocomplete=\"off\" \n\n\t\t\t\t\t\t\t\t\t\t\tvalue=\"1 chambre - 1 adulte\"\/>\n\n\n\n\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t<div class=\"rc-dropdown-menu fw\" id=\"traveler_details\">\n\n\t\t\t\t\t\t\t\t\t\t<div id=\"rooms_container\">\n\n\t\t\t\t\t\t\t\t\t\t\t<div id=\"room_0_container\" class=\"rm-cnt\"><!--  ROOM CONTAINER  -->\n\n\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"rc-row\">\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"rc-col-xs-12\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"room-error\" id=\"room_error_0\"><\/span>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"rc-col-xs-6\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"rc-text-right room-num-div\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"room-num-span\" id=\"room-num-span-0\">chambre 1<\/span>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"rc-col-xs-6\"><\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"rc-row\">\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"rc-col-xs-6 rc-text-center\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"rc-text-center div-room-adult-occupancy flex\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"name-span\">adultes<\/span>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"icon-span\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-male occupancy-icon src-occupancy-icon\" aria-hidden=\"true\"><\/i>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"rc-col-xs-6 rc-text-align-auto\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\" rc-text-center inline-block div-room-adult-quantity\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"box-btn-round btn-less disabled_btn\" id=\"adults_less_0\">-<\/span>\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t<div class=\"form-search-div\" >\n\n\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span id=\"adults_span_0\" class=\"src-span\">1<\/span>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input type=\"hidden\" id=\"adults_0\" name=\"adults\" value=\"1\"\/>\n\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"box-btn-round btn-plus \" id=\"adults_more_0\">+<\/span>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"rc-row  children-row\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"rc-col-xs-6 rc-text-center app_child_cnt\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\" rc-text-center div-room-child-occupancy flex\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"name-span\">enfants<\/span>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"icon-span\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-child occupancy-icon src-occupancy-icon\" aria-hidden=\"true\"><\/i>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"rc-col-xs-6 rc-text-align-auto app_child_cnt\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\" rc-text-center inline-block div-room-child-quantity\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"box-btn-round btn-less disabled_btn\" id=\"children_less_0\">-<\/span>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"form-search-div\">\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"src-span\" id=\"children_span_0\">0<\/span>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input type=\"hidden\" name=\"children\" id=\"children_0\" value=\"0\"\/>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"box-btn-round btn-plus \" id=\"children_more_0\">+<\/span>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"rc-row  children-row\" id=\"room_0_children_append_container\"><!--  START CHILDREN AGES   -->\n\n\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\t<!--  END CHILDREN AGES   -->\n\n\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- END ROOM CONTAINER  -->\n\n\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t<div id=\"room_add_div\" class=\"rc-text-right\"> \n\n\t\t\t\t\t\t\t\t\t\t<hr class=\"last-hr\">\n\n\t\t\t\t\t\t\t\t\t\t<span id=\"room_add_span\">ajouter de la place +<\/span>\n\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t<div id=\"close-btn-div\" class=\"rc-text-center\">\n\n\t\t\t\t\t\t\t\t\t\t\t<button class=\"button btn btn-block  be-btn\" id=\"close_dropdown\" type=\"button\" class=\"rc-text-center\" aria-label=\"close_dropdown\">\n\n\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"rc-close-btn\">fini<\/span>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\t<\/button>\n\n\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<\/div>\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t<\/div>\n\n\n\n\n\n\n\n\t\t\t\t\t\t\t<div class=\"rc-col-xs-12 rc-col-sm-6 rc-col-md-3 rc-col-lg-3 promotional-code-input\">\n\n\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t<div class=\"rc-input-group\" id=\"promo_search_group\">\n\n\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t<span class=\"input-group-addon\" id=\"calendar_search_span\" ><i class=\"fa fa-tag src-icon\" aria-hidden=\"true\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<label class=\"for\" for=\"pin\">.<\/label>\n\t\t\t\t\t\t\t\t\t<input class=\"form-control\" id=\"pin\" name=\"pin\" placeholder=\"code promotionnel\"\/>\n\n\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t<\/div>\n\n\n\n\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t<div class=\"rc-col-xs-12 rc-col-sm-6 rc-col-md-2 rc-col-lg-3 rc-text-center\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t    \n\t\t\t\t\t\t\t\t<button class=\"button btn btn-block  be-btn\" type=\"button\" id=\"btn-search\" aria-label=\"btn-search\">\n\n\t\t\t\t\t\t\t\t\t<i class=\"fa fa-search\" aria-hidden=\"true\"> Buscar<\/i>\n\n\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t<\/button>\n\n\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t \n\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t<\/form>\n\n\t\t<\/div> \n\n\t\t\n\n\n\n\t<script>\n\n\n\n\tvar openDropdownsOnTop=false;\n\n\tvar str_adult=\" adulte\";\n\n\tvar str_adults=\" adultes\";\n\n\tvar str_child=\" enfant\";\n\n\tvar str_children=\" enfants\";\n\n\tvar str_room=\"chambre\";\n\n\tvar str_rooms=\"pi\u00e8ces\";\n\n\tvar str_remove_room=\"retirer la cam\u00e9ra\";\n\n\tvar str_room_error=\"veuillez ajouter 1 personne ou supprimer la chambre\";\n\n\tvar str_age=\"\u00c2ge\";\n\n\tvar str_night=\"nuit\";\n\n\tvar str_nights=\"nuits\";\n\n\n\n\tvar locale='fr';\n\n\tvar color='';\n\n\t\tif (color!=\"\"){ \n\n\t\t\n\n\t\tdocument.documentElement.style.setProperty('--blu-color', '#'+color);\n\n\t\tdocument.documentElement.style.setProperty('--litepicker-is-in-range-color', '#ffffff');\n\n\t\tdocument.documentElement.style.setProperty('--litepicker-is-in-range-color-bg', '#'+color);\n\n\t\tdocument.documentElement.style.setProperty('--litepicker-is-in-range-brightness', '1.2');\n\n\t\tdocument.documentElement.style.setProperty('--litepicker-day-color-hover', '#'+color);\n\n\t\tdocument.documentElement.style.setProperty('--litepicker-button-prev-month-color-hover', '#'+color);\n\n\t\tdocument.documentElement.style.setProperty('--litepicker-button-next-month-color-hover', '#'+color);\n\n\t\t\n\n\t\tdocument.documentElement.style.setProperty('--litepicker-is-start-color', '#ffffff');\n\n\t\tdocument.documentElement.style.setProperty('--litepicker-is-start-color-bg', '#'+color);\n\n\t\tdocument.documentElement.style.setProperty('--litepicker-is-end-color', '#ffffff');\n\n\t\tdocument.documentElement.style.setProperty('--litepicker-is-end-color-bg', '#'+color);\n\n\t}\n\n\t<\/script>\t\n\n\t\t\n\n<div class=\"wpb_text_column\" ><div class=\"wpb_wrapper\">\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_b06a40b2 height_large\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row type_default valign_middle\"><div class=\"vc_col-sm-6 wpb_column vc_column_container animate_afb\"><div class=\"vc_column-inner us_custom_013083dc\"><div class=\"wpb_wrapper\"><div class=\"w-image align_none\"><div class=\"w-image-h\"><img width=\"736\" height=\"695\" src=\"data:image\/svg+xml,%3Csvg xmlns=%22http:\/\/www.w3.org\/2000\/svg%22 viewBox=%220 0 736 695%22%3E%3C\/svg%3E\" data-lazy-type=\"image\" data-src=\"https:\/\/www.hotelcesaraugusta.com\/wp-content\/uploads\/2023\/03\/entrada-hotel-cesaraugusta-3.jpg\" class=\"lazy lazy-hidden attachment-large size-large\" alt=\"Entrada Hotel Cesaraugusta\" loading=\"lazy\" srcset=\"\" data-srcset=\"https:\/\/www.hotelcesaraugusta.com\/wp-content\/uploads\/2023\/03\/entrada-hotel-cesaraugusta-3.jpg 736w, https:\/\/www.hotelcesaraugusta.com\/wp-content\/uploads\/2023\/03\/entrada-hotel-cesaraugusta-3-300x283.jpg 300w, https:\/\/www.hotelcesaraugusta.com\/wp-content\/uploads\/2023\/03\/entrada-hotel-cesaraugusta-3-635x600.jpg 635w, https:\/\/www.hotelcesaraugusta.com\/wp-content\/uploads\/2023\/03\/entrada-hotel-cesaraugusta-3-424x400.jpg 424w\" sizes=\"(max-width: 736px) 100vw, 736px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container animate_afc services\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column us_custom_8d5aa4e2\" ><div class=\"wpb_wrapper\"><h2>Hotel Cesaraugusta<\/h2>\n<\/div><\/div><div class=\"wpb_text_column us_custom_67dba568 has_text_color\" ><div class=\"wpb_wrapper\"><p>Ambianc\u00e9 dans l\u2019Antique Rome<\/p>\n<\/div><\/div><div class=\"w-separator size_medium\"><\/div><div class=\"g-cols wpb_row  type_default valign_top vc_inner\"><div class=\"vc_col-sm-12 wpb_column vc_column_container animate_afb\" style=\"animation-delay:0.3s;\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column us_custom_09d3e09f\" ><div class=\"wpb_wrapper\"><p>Situ\u00e9 au centre-ville, avec une bonne connexion avec les principales stations de trains et AVE (TGV) gr\u00e2ce au transport public dans le cas de la Station Delicias ou 4 minutes \u00e0 pied jusqu\u2019\u00e0 la station Goya ou Portillo.<\/p>\n<p>Notre logement, proche et familier, donne service depuis plus de 35 ans aux touristes et\/ou personnes d\u2019affaires dans la ville de Saragosse de la forme plus professionnelle possible.<\/p>\n<p>Ambianc\u00e9 dans l\u2019Antique Rome, l\u2019h\u00f4tel Cesaraugusta combine les traits de ses origines avec la premi\u00e8re ligne de services pour un s\u00e9jour ad\u00e9quat et confortable.<\/p>\n<p>Pour votre voyage de loisir\/affaire, avec la meilleure qualit\u00e9 prix dans la capitale aragonaise.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_edddf27a height_huge\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row type_default valign_top\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column us_custom_27f89b3a\" ><div class=\"wpb_wrapper\"><p>Que vous proposons-nous ?<\/p>\n<\/div><\/div><div class=\"wpb_text_column us_custom_41119b1a\" ><div class=\"wpb_wrapper\"><p>Services pour un s\u00e9jour ad\u00e9quat et confortable<\/p>\n<\/div><\/div><div class=\"g-cols wpb_row  us_custom_f029a2ba type_default valign_top vc_inner\"><div class=\"vc_col-sm-3 vc_col-xs-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_eb849559 iconpos_top style_default color_custom align_center\"><div class=\"w-iconbox-icon\" style=\"font-size:70px;color:#f63b2c;\"><i class=\"fal fa-book-reader\"><\/i><\/div><div class=\"w-iconbox-meta\"><span class=\"w-iconbox-title\" style=\"font-size:1.3rem;\">R\u00e9ception 24h<\/span><div class=\"w-iconbox-text\"><p>Attention constante, accueil ouvert. Service garanti 24h\/24<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-3 vc_col-xs-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_eb849559 iconpos_top style_default color_custom align_center\"><div class=\"w-iconbox-icon\" style=\"font-size:70px;color:#f63b2c;\"><i class=\"fal fa-sort-circle\"><\/i><\/div><div class=\"w-iconbox-meta\"><span class=\"w-iconbox-title\" style=\"font-size:1.3rem;\">Ascenseur<\/span><div class=\"w-iconbox-text\"><p>Ascenseur disponible \u00e0 tout moment pour votre confort dans l&rsquo;h\u00f4tel<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-3 vc_col-xs-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_eb849559 iconpos_top style_default color_custom align_center\"><div class=\"w-iconbox-icon\" style=\"font-size:70px;color:#f63b2c;\"><i class=\"fal fa-heat\"><\/i><\/div><div class=\"w-iconbox-meta\"><span class=\"w-iconbox-title\" style=\"font-size:1.3rem;\">Chauffage<\/span><div class=\"w-iconbox-text\"><p>Chauffage dans les chambres pour votre confort<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-3 vc_col-xs-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_eb849559 iconpos_top style_default color_custom align_center\"><div class=\"w-iconbox-icon\" style=\"font-size:70px;color:#f63b2c;\"><i class=\"fal fa-air-conditioner\"><\/i><\/div><div class=\"w-iconbox-meta\"><span class=\"w-iconbox-title\" style=\"font-size:1.3rem;\">Climatisation<\/span><div class=\"w-iconbox-text\"><p>Climatisation disponible pour votre confort \u00e0 tout moment<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"g-cols wpb_row  us_custom_f029a2ba type_default valign_top vc_inner\"><div class=\"vc_col-sm-3 vc_col-xs-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_eb849559 iconpos_top style_default color_custom align_center\"><div class=\"w-iconbox-icon\" style=\"font-size:70px;color:#f63b2c;\"><i class=\"fal fa-lock-alt\"><\/i><\/div><div class=\"w-iconbox-meta\"><span class=\"w-iconbox-title\" style=\"font-size:1.3rem;\">Caisse de S\u00e9curit\u00e9<\/span><div class=\"w-iconbox-text\"><p>Coffre-fort disponible pour prot\u00e9ger vos effets personnels<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-3 vc_col-xs-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_eb849559 iconpos_top style_default color_custom align_center\"><div class=\"w-iconbox-icon\" style=\"font-size:70px;color:#f63b2c;\"><i class=\"fal fa-coffee\"><\/i><\/div><div class=\"w-iconbox-meta\"><span class=\"w-iconbox-title\" style=\"font-size:1.3rem;\">Petit d\u00e9jeuner<\/span><div class=\"w-iconbox-text\"><p>Petit-d\u00e9jeuner vari\u00e9 et d\u00e9licieux pour bien commencer la journ\u00e9e<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-3 vc_col-xs-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_eb849559 iconpos_top style_default color_custom align_center\"><div class=\"w-iconbox-icon\" style=\"font-size:70px;color:#f63b2c;\"><i class=\"fal fa-parking\"><\/i><\/div><div class=\"w-iconbox-meta\"><span class=\"w-iconbox-title\" style=\"font-size:1.3rem;\">Parking de l&rsquo;h\u00f4tel et chargeur \u00e9lectrique<\/span><div class=\"w-iconbox-text\"><p>Garez-vous confortablement et rechargez votre voiture dans notre h\u00f4tel<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-3 vc_col-xs-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_eb849559 iconpos_top style_default color_custom align_center\"><div class=\"w-iconbox-icon\" style=\"font-size:70px;color:#f63b2c;\"><i class=\"fal fa-users\"><\/i><\/div><div class=\"w-iconbox-meta\"><span class=\"w-iconbox-title\" style=\"font-size:1.3rem;\">Salle de Conf\u00e9rences<\/span><div class=\"w-iconbox-text\"><p>Salle de conf\u00e9rence disponible, r\u00e9servez d\u00e8s maintenant pour votre r\u00e9union importante<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"g-cols wpb_row  type_default valign_top vc_inner\"><div class=\"vc_col-sm-3 vc_col-xs-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_eb849559 iconpos_top style_default color_custom align_center\"><div class=\"w-iconbox-icon\" style=\"font-size:70px;color:#f63b2c;\"><i class=\"fal fa-washer\"><\/i><\/div><div class=\"w-iconbox-meta\"><span class=\"w-iconbox-title\" style=\"font-size:1.3rem;\">Service de Blanchisserie<\/span><div class=\"w-iconbox-text\"><p>Vos v\u00eatements toujours propres \u00e0 tout moment<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-3 vc_col-xs-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_eb849559 iconpos_top style_default color_custom align_center\"><div class=\"w-iconbox-icon\" style=\"font-size:70px;color:#f63b2c;\"><i class=\"fal fa-wifi\"><\/i><\/div><div class=\"w-iconbox-meta\"><span class=\"w-iconbox-title\" style=\"font-size:1.3rem;\">Wifi<\/span><div class=\"w-iconbox-text\"><p>Se connecter maintenant! Connexion Wi-Fi disponible pour les invit\u00e9s<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-3 vc_col-xs-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_eb849559 iconpos_top style_default color_custom align_center\"><div class=\"w-iconbox-icon\" style=\"font-size:70px;color:#f63b2c;\"><i class=\"fal fa-tv\"><\/i><\/div><div class=\"w-iconbox-meta\"><span class=\"w-iconbox-title\" style=\"font-size:1.3rem;\">TV Plane 32<\/span><div class=\"w-iconbox-text\"><p>Asseyez-vous et d\u00e9tendez-vous sur l&rsquo;une de nos cha\u00eenes<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-3 vc_col-xs-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_eb849559 iconpos_top style_default color_custom align_center\"><div class=\"w-iconbox-icon\" style=\"font-size:70px;color:#f63b2c;\"><i class=\"fal fa-dog\"><\/i><\/div><div class=\"w-iconbox-meta\"><span class=\"w-iconbox-title\" style=\"font-size:1.3rem;\">Animaux non admis<\/span><div class=\"w-iconbox-text\"><p>Nous sommes d\u00e9sol\u00e9s. Profitez de nos services<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_large\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row type_default valign_top\"><div class=\"vc_col-sm-12 wpb_column vc_column_container animate_afb\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column us_custom_eb849559\" ><div class=\"wpb_wrapper\"><h2>Chambres pour toute sorte de s\u00e9jours<\/h2>\n<\/div><\/div><div class=\"w-separator size_medium\"><\/div><div class=\"g-cols wpb_row  type_default valign_top vc_inner\"><div class=\"vc_col-sm-4 wpb_column vc_column_container has-link\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-image align_none\"><div class=\"w-image-h\"><img width=\"683\" height=\"683\" src=\"data:image\/svg+xml,%3Csvg xmlns=%22http:\/\/www.w3.org\/2000\/svg%22 viewBox=%220 0 683 683%22%3E%3C\/svg%3E\" data-lazy-type=\"image\" data-src=\"https:\/\/www.hotelcesaraugusta.com\/wp-content\/uploads\/2023\/03\/ofertas-hotel-cesaraugusta-2.jpg\" class=\"lazy lazy-hidden attachment-large size-large\" alt=\"Ofertas hotel Cesaraugusta\" loading=\"lazy\" srcset=\"\" data-srcset=\"https:\/\/www.hotelcesaraugusta.com\/wp-content\/uploads\/2023\/03\/ofertas-hotel-cesaraugusta-2.jpg 683w, https:\/\/www.hotelcesaraugusta.com\/wp-content\/uploads\/2023\/03\/ofertas-hotel-cesaraugusta-2-300x300.jpg 300w, https:\/\/www.hotelcesaraugusta.com\/wp-content\/uploads\/2023\/03\/ofertas-hotel-cesaraugusta-2-150x150.jpg 150w, https:\/\/www.hotelcesaraugusta.com\/wp-content\/uploads\/2023\/03\/ofertas-hotel-cesaraugusta-2-600x600.jpg 600w, https:\/\/www.hotelcesaraugusta.com\/wp-content\/uploads\/2023\/03\/ofertas-hotel-cesaraugusta-2-400x400.jpg 400w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/div><\/div><div class=\"wpb_text_column us_custom_78f23fad\" ><div class=\"wpb_wrapper\"><p>Offres<\/p>\n<\/div><\/div><div class=\"wpb_text_column\" ><div class=\"wpb_wrapper\"><p>D\u00e9couvre les offres que l\u2019H\u00f4tel Cesaraugusta \u00e0 pr\u00e9par\u00e9 pour vous.<\/p>\n<\/div><\/div><\/div><a class=\"vc_column-link smooth-scroll\" href=\"https:\/\/www.hotelcesaraugusta.com\/fr\/offerts\/\" title=\"Ofertas\"><\/a><\/div><\/div><div class=\"vc_col-sm-4 wpb_column vc_column_container has-link\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-image align_none\"><div class=\"w-image-h\"><img width=\"683\" height=\"683\" src=\"data:image\/svg+xml,%3Csvg xmlns=%22http:\/\/www.w3.org\/2000\/svg%22 viewBox=%220 0 683 683%22%3E%3C\/svg%3E\" data-lazy-type=\"image\" data-src=\"https:\/\/www.hotelcesaraugusta.com\/wp-content\/uploads\/2023\/03\/habitaciones-hote-cesaraugusta-2.jpg\" class=\"lazy lazy-hidden attachment-large size-large\" alt=\"Habitaciones hotel Cesaraugusta\" loading=\"lazy\" srcset=\"\" data-srcset=\"https:\/\/www.hotelcesaraugusta.com\/wp-content\/uploads\/2023\/03\/habitaciones-hote-cesaraugusta-2.jpg 683w, https:\/\/www.hotelcesaraugusta.com\/wp-content\/uploads\/2023\/03\/habitaciones-hote-cesaraugusta-2-300x300.jpg 300w, https:\/\/www.hotelcesaraugusta.com\/wp-content\/uploads\/2023\/03\/habitaciones-hote-cesaraugusta-2-150x150.jpg 150w, https:\/\/www.hotelcesaraugusta.com\/wp-content\/uploads\/2023\/03\/habitaciones-hote-cesaraugusta-2-600x600.jpg 600w, https:\/\/www.hotelcesaraugusta.com\/wp-content\/uploads\/2023\/03\/habitaciones-hote-cesaraugusta-2-400x400.jpg 400w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/div><\/div><div class=\"wpb_text_column us_custom_78f23fad\" ><div class=\"wpb_wrapper\"><p>Chambres<\/p>\n<\/div><\/div><div class=\"wpb_text_column\" ><div class=\"wpb_wrapper\"><p>40 chambres climatis\u00e9es, confortables et d\u00e9cor\u00e9es, avec une grande amplitude avec un design \u00e9l\u00e9gant et fonctionnel.<\/p>\n<\/div><\/div><\/div><a class=\"vc_column-link smooth-scroll\" href=\"https:\/\/www.hotelcesaraugusta.com\/fr\/chambres-a-saragosse\/\" title=\"Habitaciones en Zaragoza\"><\/a><\/div><\/div><div class=\"vc_col-sm-4 wpb_column vc_column_container has-link\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-image align_none\"><div class=\"w-image-h\"><img width=\"683\" height=\"683\" src=\"data:image\/svg+xml,%3Csvg xmlns=%22http:\/\/www.w3.org\/2000\/svg%22 viewBox=%220 0 683 683%22%3E%3C\/svg%3E\" data-lazy-type=\"image\" data-src=\"https:\/\/www.hotelcesaraugusta.com\/wp-content\/uploads\/2023\/03\/apartamentos-hotel-cesaraugusta2-1.jpg\" class=\"lazy lazy-hidden attachment-large size-large\" alt=\"Apartamentos hotel Cesaraugusta\" loading=\"lazy\" srcset=\"\" data-srcset=\"https:\/\/www.hotelcesaraugusta.com\/wp-content\/uploads\/2023\/03\/apartamentos-hotel-cesaraugusta2-1.jpg 683w, https:\/\/www.hotelcesaraugusta.com\/wp-content\/uploads\/2023\/03\/apartamentos-hotel-cesaraugusta2-1-300x300.jpg 300w, https:\/\/www.hotelcesaraugusta.com\/wp-content\/uploads\/2023\/03\/apartamentos-hotel-cesaraugusta2-1-150x150.jpg 150w, https:\/\/www.hotelcesaraugusta.com\/wp-content\/uploads\/2023\/03\/apartamentos-hotel-cesaraugusta2-1-600x600.jpg 600w, https:\/\/www.hotelcesaraugusta.com\/wp-content\/uploads\/2023\/03\/apartamentos-hotel-cesaraugusta2-1-400x400.jpg 400w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/div><\/div><div class=\"wpb_text_column us_custom_78f23fad\" ><div class=\"wpb_wrapper\"><p>Appartements<\/p>\n<\/div><\/div><div class=\"wpb_text_column\" ><div class=\"wpb_wrapper\"><p>M\u00eame pour les familles comme pour le client individuel et sp\u00e9cialement indiqu\u00e9s pour des longs s\u00e9jours.<\/p>\n<\/div><\/div><\/div><a class=\"vc_column-link smooth-scroll\" href=\"https:\/\/www.hotelcesaraugusta.com\/fr\/appartements-a-saragosse\/\" title=\"Apartamentos en Zaragoza\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_821ea863 height_medium width_full\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row type_default valign_top\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><section class=\"l-section wpb_row us_custom_3b551fb2 height_large width_full\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row type_default valign_top\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column us_custom_aadc10d8 has_text_color\" ><div class=\"wpb_wrapper\"><h2>Contactez avec nous<\/h2>\n<p>Contactez avec nous et nous vous informerons de toutes nos offres et nouveaut\u00e9s<\/p>\n<\/div><\/div><div class=\"w-hwrapper align_center valign_top\"><div class=\"w-btn-wrapper width_auto align_center\"><a class=\"w-btn us-btn-style_8 us_custom_e28183d5\" href=\"https:\/\/www.hotelcesaraugusta.com\/fr\/contactez-avec-nous\/\" title=\"Contactar\"><span class=\"w-btn-label\">Contactez<\/span><\/a><\/div><div class=\"w-btn-wrapper width_auto align_center\"><a class=\"w-btn us-btn-style_8 us_custom_e28183d5\" href=\"tel:976282727\" title=\"Contactar\"><span class=\"w-btn-label\">Appelle-nous<\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n<\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ton h\u00f4tel de confiance \u00e0 Saragosse - Hotel Cesaraugusta<\/title>\n<meta name=\"description\" content=\"Profitez d&#039;un h\u00e9bergement situ\u00e9 dans la Rome antique. L&#039;h\u00f4tel Cesaraugusta est proche et familier et est situ\u00e9 dans le centre-ville\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hotelcesaraugusta.com\/fr\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ton h\u00f4tel de confiance \u00e0 Saragosse - Hotel Cesaraugusta\" \/>\n<meta property=\"og:description\" content=\"Profitez d&#039;un h\u00e9bergement situ\u00e9 dans la Rome antique. L&#039;h\u00f4tel Cesaraugusta est proche et familier et est situ\u00e9 dans le centre-ville\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hotelcesaraugusta.com\/fr\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel Cesaraugusta\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-22T07:34:35+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.hotelcesaraugusta.com\/#organization\",\"name\":\"Hotel Cesaraugusta\",\"url\":\"https:\/\/www.hotelcesaraugusta.com\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.hotelcesaraugusta.com\/#logo\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.hotelcesaraugusta.com\/wp-content\/uploads\/2020\/09\/logo-hotel-cesaraugusta.jpg\",\"contentUrl\":\"https:\/\/www.hotelcesaraugusta.com\/wp-content\/uploads\/2020\/09\/logo-hotel-cesaraugusta.jpg\",\"width\":200,\"height\":91,\"caption\":\"Hotel Cesaraugusta\"},\"image\":{\"@id\":\"https:\/\/www.hotelcesaraugusta.com\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.hotelcesaraugusta.com\/#website\",\"url\":\"https:\/\/www.hotelcesaraugusta.com\/\",\"name\":\"Hotel Cesaraugusta\",\"description\":\"-Web Oficial-Tu hotel de confianza en Zaragoza\",\"publisher\":{\"@id\":\"https:\/\/www.hotelcesaraugusta.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.hotelcesaraugusta.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.hotelcesaraugusta.com\/fr\/#webpage\",\"url\":\"https:\/\/www.hotelcesaraugusta.com\/fr\/\",\"name\":\"Ton h\\u00f4tel de confiance \\u00e0 Saragosse - Hotel Cesaraugusta\",\"isPartOf\":{\"@id\":\"https:\/\/www.hotelcesaraugusta.com\/#website\"},\"datePublished\":\"2024-03-20T07:37:14+00:00\",\"dateModified\":\"2024-03-22T07:34:35+00:00\",\"description\":\"Profitez d'un h\\u00e9bergement situ\\u00e9 dans la Rome antique. L'h\\u00f4tel Cesaraugusta est proche et familier et est situ\\u00e9 dans le centre-ville\",\"breadcrumb\":{\"@id\":\"https:\/\/www.hotelcesaraugusta.com\/fr\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.hotelcesaraugusta.com\/fr\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.hotelcesaraugusta.com\/fr\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.hotelcesaraugusta.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ton h\\u00f4tel de confiance \\u00e0 Saragosse\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ton h\u00f4tel de confiance \u00e0 Saragosse - Hotel Cesaraugusta","description":"Profitez d'un h\u00e9bergement situ\u00e9 dans la Rome antique. L'h\u00f4tel Cesaraugusta est proche et familier et est situ\u00e9 dans le centre-ville","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hotelcesaraugusta.com\/fr\/","og_locale":"fr_FR","og_type":"article","og_title":"Ton h\u00f4tel de confiance \u00e0 Saragosse - Hotel Cesaraugusta","og_description":"Profitez d'un h\u00e9bergement situ\u00e9 dans la Rome antique. L'h\u00f4tel Cesaraugusta est proche et familier et est situ\u00e9 dans le centre-ville","og_url":"https:\/\/www.hotelcesaraugusta.com\/fr\/","og_site_name":"Hotel Cesaraugusta","article_modified_time":"2024-03-22T07:34:35+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture est.":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/www.hotelcesaraugusta.com\/#organization","name":"Hotel Cesaraugusta","url":"https:\/\/www.hotelcesaraugusta.com\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/www.hotelcesaraugusta.com\/#logo","inLanguage":"fr-FR","url":"https:\/\/www.hotelcesaraugusta.com\/wp-content\/uploads\/2020\/09\/logo-hotel-cesaraugusta.jpg","contentUrl":"https:\/\/www.hotelcesaraugusta.com\/wp-content\/uploads\/2020\/09\/logo-hotel-cesaraugusta.jpg","width":200,"height":91,"caption":"Hotel Cesaraugusta"},"image":{"@id":"https:\/\/www.hotelcesaraugusta.com\/#logo"}},{"@type":"WebSite","@id":"https:\/\/www.hotelcesaraugusta.com\/#website","url":"https:\/\/www.hotelcesaraugusta.com\/","name":"Hotel Cesaraugusta","description":"-Web Oficial-Tu hotel de confianza en Zaragoza","publisher":{"@id":"https:\/\/www.hotelcesaraugusta.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hotelcesaraugusta.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.hotelcesaraugusta.com\/fr\/#webpage","url":"https:\/\/www.hotelcesaraugusta.com\/fr\/","name":"Ton h\u00f4tel de confiance \u00e0 Saragosse - Hotel Cesaraugusta","isPartOf":{"@id":"https:\/\/www.hotelcesaraugusta.com\/#website"},"datePublished":"2024-03-20T07:37:14+00:00","dateModified":"2024-03-22T07:34:35+00:00","description":"Profitez d'un h\u00e9bergement situ\u00e9 dans la Rome antique. L'h\u00f4tel Cesaraugusta est proche et familier et est situ\u00e9 dans le centre-ville","breadcrumb":{"@id":"https:\/\/www.hotelcesaraugusta.com\/fr\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hotelcesaraugusta.com\/fr\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.hotelcesaraugusta.com\/fr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.hotelcesaraugusta.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Ton h\u00f4tel de confiance \u00e0 Saragosse"}]}]}},"_links":{"self":[{"href":"https:\/\/www.hotelcesaraugusta.com\/fr\/wp-json\/wp\/v2\/pages\/12599"}],"collection":[{"href":"https:\/\/www.hotelcesaraugusta.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hotelcesaraugusta.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hotelcesaraugusta.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hotelcesaraugusta.com\/fr\/wp-json\/wp\/v2\/comments?post=12599"}],"version-history":[{"count":10,"href":"https:\/\/www.hotelcesaraugusta.com\/fr\/wp-json\/wp\/v2\/pages\/12599\/revisions"}],"predecessor-version":[{"id":15250,"href":"https:\/\/www.hotelcesaraugusta.com\/fr\/wp-json\/wp\/v2\/pages\/12599\/revisions\/15250"}],"wp:attachment":[{"href":"https:\/\/www.hotelcesaraugusta.com\/fr\/wp-json\/wp\/v2\/media?parent=12599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}